{"id":4092,"date":"2025-04-08T11:51:36","date_gmt":"2025-04-08T09:51:36","guid":{"rendered":"https:\/\/www.ecovis.com\/a29-stralsund\/?page_id=4092"},"modified":"2025-05-07T17:32:24","modified_gmt":"2025-05-07T15:32:24","slug":"stellenanzeigen","status":"publish","type":"page","link":"https:\/\/www.ecovis.com\/stralsund\/karriere\/stellenanzeigen\/","title":{"rendered":"Stellenanzeigen"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":28,"featured_media":0,"parent":3781,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"services.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-4092","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ecovis Stralsund Steuerberater - Stellenanzeigen<\/title>\n<meta name=\"description\" content=\"Ecovis Stralsund\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecovis.com\/stralsund\/karriere\/stellenanzeigen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ecovis Stralsund Steuerberater - Stellenanzeigen\" \/>\n<meta property=\"og:description\" content=\"Ecovis Stralsund\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecovis.com\/stralsund\/karriere\/stellenanzeigen\/\" \/>\n<meta property=\"og:site_name\" content=\"Ecovis Stralsund\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-07T15:32:24+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ecovis.com\\\/stralsund\\\/karriere\\\/stellenanzeigen\\\/\",\"url\":\"https:\\\/\\\/www.ecovis.com\\\/stralsund\\\/karriere\\\/stellenanzeigen\\\/\",\"name\":\"Ecovis Stralsund Steuerberater - Stellenanzeigen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ecovis.com\\\/stralsund\\\/#website\"},\"datePublished\":\"2025-04-08T09:51:36+00:00\",\"dateModified\":\"2025-05-07T15:32:24+00:00\",\"description\":\"Ecovis Stralsund\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ecovis.com\\\/stralsund\\\/karriere\\\/stellenanzeigen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ecovis.com\\\/stralsund\\\/karriere\\\/stellenanzeigen\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ecovis.com\\\/stralsund\\\/karriere\\\/stellenanzeigen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Ecovis Global\",\"item\":\"https:\\\/\\\/www.ecovis.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ecovis.com\\\/stralsund\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Karriere\",\"item\":\"https:\\\/\\\/www.ecovis.com\\\/stralsund\\\/karriere\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Stellenanzeigen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ecovis.com\\\/stralsund\\\/#website\",\"url\":\"https:\\\/\\\/www.ecovis.com\\\/stralsund\\\/\",\"name\":\"Ecovis.com\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ecovis.com\\\/stralsund\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ecovis Stralsund Steuerberater - Stellenanzeigen","description":"Ecovis Stralsund","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecovis.com\/stralsund\/karriere\/stellenanzeigen\/","og_locale":"de_DE","og_type":"article","og_title":"Ecovis Stralsund Steuerberater - Stellenanzeigen","og_description":"Ecovis Stralsund","og_url":"https:\/\/www.ecovis.com\/stralsund\/karriere\/stellenanzeigen\/","og_site_name":"Ecovis Stralsund","article_modified_time":"2025-05-07T15:32:24+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ecovis.com\/stralsund\/karriere\/stellenanzeigen\/","url":"https:\/\/www.ecovis.com\/stralsund\/karriere\/stellenanzeigen\/","name":"Ecovis Stralsund Steuerberater - Stellenanzeigen","isPartOf":{"@id":"https:\/\/www.ecovis.com\/stralsund\/#website"},"datePublished":"2025-04-08T09:51:36+00:00","dateModified":"2025-05-07T15:32:24+00:00","description":"Ecovis Stralsund","breadcrumb":{"@id":"https:\/\/www.ecovis.com\/stralsund\/karriere\/stellenanzeigen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ecovis.com\/stralsund\/karriere\/stellenanzeigen\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ecovis.com\/stralsund\/karriere\/stellenanzeigen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Ecovis Global","item":"https:\/\/www.ecovis.com\/"},{"@type":"ListItem","position":2,"name":"Home","item":"https:\/\/www.ecovis.com\/stralsund\/"},{"@type":"ListItem","position":3,"name":"Karriere","item":"https:\/\/www.ecovis.com\/stralsund\/karriere\/"},{"@type":"ListItem","position":4,"name":"Stellenanzeigen"}]},{"@type":"WebSite","@id":"https:\/\/www.ecovis.com\/stralsund\/#website","url":"https:\/\/www.ecovis.com\/stralsund\/","name":"Ecovis.com","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ecovis.com\/stralsund\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.ecovis.com\/stralsund\/wp-json\/wp\/v2\/pages\/4092","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecovis.com\/stralsund\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ecovis.com\/stralsund\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecovis.com\/stralsund\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecovis.com\/stralsund\/wp-json\/wp\/v2\/comments?post=4092"}],"version-history":[{"count":7,"href":"https:\/\/www.ecovis.com\/stralsund\/wp-json\/wp\/v2\/pages\/4092\/revisions"}],"predecessor-version":[{"id":4238,"href":"https:\/\/www.ecovis.com\/stralsund\/wp-json\/wp\/v2\/pages\/4092\/revisions\/4238"}],"up":[{"embeddable":true,"href":"https:\/\/www.ecovis.com\/stralsund\/wp-json\/wp\/v2\/pages\/3781"}],"wp:attachment":[{"href":"https:\/\/www.ecovis.com\/stralsund\/wp-json\/wp\/v2\/media?parent=4092"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}