{"id":3781,"date":"2025-03-25T17:03:18","date_gmt":"2025-03-25T16:03:18","guid":{"rendered":"https:\/\/www.ecovis.com\/a29-stralsund\/?page_id=3781"},"modified":"2025-08-29T22:41:08","modified_gmt":"2025-08-29T20:41:08","slug":"karriere","status":"publish","type":"page","link":"https:\/\/www.ecovis.com\/stralsund\/karriere\/","title":{"rendered":"Karriere"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":28,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"karriere-allgemein.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-3781","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Besser mit dir - Karriere bei Ecovis Stralsund<\/title>\n<meta name=\"description\" content=\"Wir sind gut in dem, was wir tun. Und wir wollen immer besser werden. Daf\u00fcr suchen wir Menschen, die zu uns passen. Jetzt bewerben!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecovis.com\/stralsund\/karriere\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Besser mit dir - Karriere bei Ecovis Stralsund\" \/>\n<meta property=\"og:description\" content=\"Wir sind gut in dem, was wir tun. Und wir wollen immer besser werden. Daf\u00fcr suchen wir Menschen, die zu uns passen. Jetzt bewerben!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecovis.com\/stralsund\/karriere\/\" \/>\n<meta property=\"og:site_name\" content=\"Ecovis Stralsund\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-29T20:41:08+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ecovis.com\\\/stralsund\\\/karriere\\\/\",\"url\":\"https:\\\/\\\/www.ecovis.com\\\/stralsund\\\/karriere\\\/\",\"name\":\"Besser mit dir - Karriere bei Ecovis Stralsund\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ecovis.com\\\/stralsund\\\/#website\"},\"datePublished\":\"2025-03-25T16:03:18+00:00\",\"dateModified\":\"2025-08-29T20:41:08+00:00\",\"description\":\"Wir sind gut in dem, was wir tun. Und wir wollen immer besser werden. Daf\u00fcr suchen wir Menschen, die zu uns passen. Jetzt bewerben!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ecovis.com\\\/stralsund\\\/karriere\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ecovis.com\\\/stralsund\\\/karriere\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ecovis.com\\\/stralsund\\\/karriere\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Ecovis Global\",\"item\":\"https:\\\/\\\/www.ecovis.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ecovis.com\\\/stralsund\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Karriere\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ecovis.com\\\/stralsund\\\/#website\",\"url\":\"https:\\\/\\\/www.ecovis.com\\\/stralsund\\\/\",\"name\":\"Ecovis.com\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ecovis.com\\\/stralsund\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Besser mit dir - Karriere bei Ecovis Stralsund","description":"Wir sind gut in dem, was wir tun. Und wir wollen immer besser werden. Daf\u00fcr suchen wir Menschen, die zu uns passen. Jetzt bewerben!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecovis.com\/stralsund\/karriere\/","og_locale":"de_DE","og_type":"article","og_title":"Besser mit dir - Karriere bei Ecovis Stralsund","og_description":"Wir sind gut in dem, was wir tun. Und wir wollen immer besser werden. Daf\u00fcr suchen wir Menschen, die zu uns passen. Jetzt bewerben!","og_url":"https:\/\/www.ecovis.com\/stralsund\/karriere\/","og_site_name":"Ecovis Stralsund","article_modified_time":"2025-08-29T20:41:08+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ecovis.com\/stralsund\/karriere\/","url":"https:\/\/www.ecovis.com\/stralsund\/karriere\/","name":"Besser mit dir - Karriere bei Ecovis Stralsund","isPartOf":{"@id":"https:\/\/www.ecovis.com\/stralsund\/#website"},"datePublished":"2025-03-25T16:03:18+00:00","dateModified":"2025-08-29T20:41:08+00:00","description":"Wir sind gut in dem, was wir tun. Und wir wollen immer besser werden. Daf\u00fcr suchen wir Menschen, die zu uns passen. Jetzt bewerben!","breadcrumb":{"@id":"https:\/\/www.ecovis.com\/stralsund\/karriere\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ecovis.com\/stralsund\/karriere\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ecovis.com\/stralsund\/karriere\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Ecovis Global","item":"https:\/\/www.ecovis.com\/"},{"@type":"ListItem","position":2,"name":"Home","item":"https:\/\/www.ecovis.com\/stralsund\/"},{"@type":"ListItem","position":3,"name":"Karriere"}]},{"@type":"WebSite","@id":"https:\/\/www.ecovis.com\/stralsund\/#website","url":"https:\/\/www.ecovis.com\/stralsund\/","name":"Ecovis.com","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ecovis.com\/stralsund\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.ecovis.com\/stralsund\/wp-json\/wp\/v2\/pages\/3781","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecovis.com\/stralsund\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ecovis.com\/stralsund\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecovis.com\/stralsund\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecovis.com\/stralsund\/wp-json\/wp\/v2\/comments?post=3781"}],"version-history":[{"count":8,"href":"https:\/\/www.ecovis.com\/stralsund\/wp-json\/wp\/v2\/pages\/3781\/revisions"}],"predecessor-version":[{"id":4304,"href":"https:\/\/www.ecovis.com\/stralsund\/wp-json\/wp\/v2\/pages\/3781\/revisions\/4304"}],"wp:attachment":[{"href":"https:\/\/www.ecovis.com\/stralsund\/wp-json\/wp\/v2\/media?parent=3781"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}