{"id":4011,"date":"2025-10-14T22:57:54","date_gmt":"2025-10-14T20:57:54","guid":{"rendered":"https:\/\/www.ecovis.com\/a46-oldenburg\/?page_id=4011"},"modified":"2025-10-15T11:16:46","modified_gmt":"2025-10-15T09:16:46","slug":"steuergestaltung","status":"publish","type":"page","link":"https:\/\/www.ecovis.com\/oldenburg\/beratungsschwerpunkte\/steuergestaltung\/","title":{"rendered":"Steuergestaltung"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":31,"featured_media":0,"parent":3771,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"leistungen-steuergestaltung.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-4011","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ecovis Oldenburg Steuerberater - Steuergestaltung<\/title>\n<meta name=\"description\" content=\"Sprechen Sie mit Ihrem Ecovis-Berater in Oldenburg \u00fcber Ihre steuerlichen Gestaltungsm\u00f6glichkeiten. Kontaktieren Sie uns jetzt!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecovis.com\/oldenburg\/beratungsschwerpunkte\/steuergestaltung\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ecovis Oldenburg Steuerberater - Steuergestaltung\" \/>\n<meta property=\"og:description\" content=\"Sprechen Sie mit Ihrem Ecovis-Berater in Oldenburg \u00fcber Ihre steuerlichen Gestaltungsm\u00f6glichkeiten. Kontaktieren Sie uns jetzt!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecovis.com\/oldenburg\/beratungsschwerpunkte\/steuergestaltung\/\" \/>\n<meta property=\"og:site_name\" content=\"Ecovis Oldenburg\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-15T09:16:46+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ecovis.com\\\/oldenburg\\\/beratungsschwerpunkte\\\/steuergestaltung\\\/\",\"url\":\"https:\\\/\\\/www.ecovis.com\\\/oldenburg\\\/beratungsschwerpunkte\\\/steuergestaltung\\\/\",\"name\":\"Ecovis Oldenburg Steuerberater - Steuergestaltung\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ecovis.com\\\/oldenburg\\\/#website\"},\"datePublished\":\"2025-10-14T20:57:54+00:00\",\"dateModified\":\"2025-10-15T09:16:46+00:00\",\"description\":\"Sprechen Sie mit Ihrem Ecovis-Berater in Oldenburg \u00fcber Ihre steuerlichen Gestaltungsm\u00f6glichkeiten. Kontaktieren Sie uns jetzt!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ecovis.com\\\/oldenburg\\\/beratungsschwerpunkte\\\/steuergestaltung\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ecovis.com\\\/oldenburg\\\/beratungsschwerpunkte\\\/steuergestaltung\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ecovis.com\\\/oldenburg\\\/beratungsschwerpunkte\\\/steuergestaltung\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Ecovis Global\",\"item\":\"https:\\\/\\\/www.ecovis.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ecovis.com\\\/oldenburg\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Schwerpunkte\",\"item\":\"https:\\\/\\\/www.ecovis.com\\\/oldenburg\\\/beratungsschwerpunkte\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Steuergestaltung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ecovis.com\\\/oldenburg\\\/#website\",\"url\":\"https:\\\/\\\/www.ecovis.com\\\/oldenburg\\\/\",\"name\":\"Ecovis.com\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ecovis.com\\\/oldenburg\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ecovis Oldenburg Steuerberater - Steuergestaltung","description":"Sprechen Sie mit Ihrem Ecovis-Berater in Oldenburg \u00fcber Ihre steuerlichen Gestaltungsm\u00f6glichkeiten. Kontaktieren Sie uns jetzt!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecovis.com\/oldenburg\/beratungsschwerpunkte\/steuergestaltung\/","og_locale":"de_DE","og_type":"article","og_title":"Ecovis Oldenburg Steuerberater - Steuergestaltung","og_description":"Sprechen Sie mit Ihrem Ecovis-Berater in Oldenburg \u00fcber Ihre steuerlichen Gestaltungsm\u00f6glichkeiten. Kontaktieren Sie uns jetzt!","og_url":"https:\/\/www.ecovis.com\/oldenburg\/beratungsschwerpunkte\/steuergestaltung\/","og_site_name":"Ecovis Oldenburg","article_modified_time":"2025-10-15T09:16:46+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ecovis.com\/oldenburg\/beratungsschwerpunkte\/steuergestaltung\/","url":"https:\/\/www.ecovis.com\/oldenburg\/beratungsschwerpunkte\/steuergestaltung\/","name":"Ecovis Oldenburg Steuerberater - Steuergestaltung","isPartOf":{"@id":"https:\/\/www.ecovis.com\/oldenburg\/#website"},"datePublished":"2025-10-14T20:57:54+00:00","dateModified":"2025-10-15T09:16:46+00:00","description":"Sprechen Sie mit Ihrem Ecovis-Berater in Oldenburg \u00fcber Ihre steuerlichen Gestaltungsm\u00f6glichkeiten. Kontaktieren Sie uns jetzt!","breadcrumb":{"@id":"https:\/\/www.ecovis.com\/oldenburg\/beratungsschwerpunkte\/steuergestaltung\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ecovis.com\/oldenburg\/beratungsschwerpunkte\/steuergestaltung\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ecovis.com\/oldenburg\/beratungsschwerpunkte\/steuergestaltung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Ecovis Global","item":"https:\/\/www.ecovis.com\/"},{"@type":"ListItem","position":2,"name":"Home","item":"https:\/\/www.ecovis.com\/oldenburg\/"},{"@type":"ListItem","position":3,"name":"Schwerpunkte","item":"https:\/\/www.ecovis.com\/oldenburg\/beratungsschwerpunkte\/"},{"@type":"ListItem","position":4,"name":"Steuergestaltung"}]},{"@type":"WebSite","@id":"https:\/\/www.ecovis.com\/oldenburg\/#website","url":"https:\/\/www.ecovis.com\/oldenburg\/","name":"Ecovis.com","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ecovis.com\/oldenburg\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.ecovis.com\/oldenburg\/wp-json\/wp\/v2\/pages\/4011","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecovis.com\/oldenburg\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ecovis.com\/oldenburg\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecovis.com\/oldenburg\/wp-json\/wp\/v2\/users\/31"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecovis.com\/oldenburg\/wp-json\/wp\/v2\/comments?post=4011"}],"version-history":[{"count":2,"href":"https:\/\/www.ecovis.com\/oldenburg\/wp-json\/wp\/v2\/pages\/4011\/revisions"}],"predecessor-version":[{"id":4446,"href":"https:\/\/www.ecovis.com\/oldenburg\/wp-json\/wp\/v2\/pages\/4011\/revisions\/4446"}],"up":[{"embeddable":true,"href":"https:\/\/www.ecovis.com\/oldenburg\/wp-json\/wp\/v2\/pages\/3771"}],"wp:attachment":[{"href":"https:\/\/www.ecovis.com\/oldenburg\/wp-json\/wp\/v2\/media?parent=4011"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}