{"id":4685,"date":"2025-09-16T09:21:22","date_gmt":"2025-09-16T07:21:22","guid":{"rendered":"https:\/\/www.ecovis.com\/muenchen\/?page_id=4685"},"modified":"2025-09-16T09:21:37","modified_gmt":"2025-09-16T07:21:37","slug":"erbrecht","status":"publish","type":"page","link":"https:\/\/www.ecovis.com\/muenchen\/beratungsschwerpunkte\/rechtsberatung\/erbrecht\/","title":{"rendered":"Erbrecht"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":28,"featured_media":0,"parent":3778,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"leistungen-erbrecht.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-4685","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ECOVIS M\u00fcnchen Steuerberater - Erbrecht<\/title>\n<meta name=\"description\" content=\"Ecovis M\u00fcnchen\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecovis.com\/muenchen\/beratungsschwerpunkte\/rechtsberatung\/erbrecht\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ECOVIS M\u00fcnchen Steuerberater - Erbrecht\" \/>\n<meta property=\"og:description\" content=\"Ecovis M\u00fcnchen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecovis.com\/muenchen\/beratungsschwerpunkte\/rechtsberatung\/erbrecht\/\" \/>\n<meta property=\"og:site_name\" content=\"Ecovis M\u00fcnchen\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-16T07:21:37+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ecovis.com\\\/muenchen\\\/beratungsschwerpunkte\\\/rechtsberatung\\\/erbrecht\\\/\",\"url\":\"https:\\\/\\\/www.ecovis.com\\\/muenchen\\\/beratungsschwerpunkte\\\/rechtsberatung\\\/erbrecht\\\/\",\"name\":\"ECOVIS M\u00fcnchen Steuerberater - Erbrecht\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ecovis.com\\\/muenchen\\\/#website\"},\"datePublished\":\"2025-09-16T07:21:22+00:00\",\"dateModified\":\"2025-09-16T07:21:37+00:00\",\"description\":\"Ecovis M\u00fcnchen\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ecovis.com\\\/muenchen\\\/beratungsschwerpunkte\\\/rechtsberatung\\\/erbrecht\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ecovis.com\\\/muenchen\\\/beratungsschwerpunkte\\\/rechtsberatung\\\/erbrecht\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ecovis.com\\\/muenchen\\\/beratungsschwerpunkte\\\/rechtsberatung\\\/erbrecht\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Ecovis Global\",\"item\":\"https:\\\/\\\/www.ecovis.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ecovis.com\\\/muenchen\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Schwerpunkte\",\"item\":\"https:\\\/\\\/www.ecovis.com\\\/muenchen\\\/beratungsschwerpunkte\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Rechtsberatung\",\"item\":\"https:\\\/\\\/www.ecovis.com\\\/muenchen\\\/beratungsschwerpunkte\\\/rechtsberatung\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Erbrecht\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ecovis.com\\\/muenchen\\\/#website\",\"url\":\"https:\\\/\\\/www.ecovis.com\\\/muenchen\\\/\",\"name\":\"Ecovis.com\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ecovis.com\\\/muenchen\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ECOVIS M\u00fcnchen Steuerberater - Erbrecht","description":"Ecovis M\u00fcnchen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecovis.com\/muenchen\/beratungsschwerpunkte\/rechtsberatung\/erbrecht\/","og_locale":"de_DE","og_type":"article","og_title":"ECOVIS M\u00fcnchen Steuerberater - Erbrecht","og_description":"Ecovis M\u00fcnchen","og_url":"https:\/\/www.ecovis.com\/muenchen\/beratungsschwerpunkte\/rechtsberatung\/erbrecht\/","og_site_name":"Ecovis M\u00fcnchen","article_modified_time":"2025-09-16T07:21:37+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ecovis.com\/muenchen\/beratungsschwerpunkte\/rechtsberatung\/erbrecht\/","url":"https:\/\/www.ecovis.com\/muenchen\/beratungsschwerpunkte\/rechtsberatung\/erbrecht\/","name":"ECOVIS M\u00fcnchen Steuerberater - Erbrecht","isPartOf":{"@id":"https:\/\/www.ecovis.com\/muenchen\/#website"},"datePublished":"2025-09-16T07:21:22+00:00","dateModified":"2025-09-16T07:21:37+00:00","description":"Ecovis M\u00fcnchen","breadcrumb":{"@id":"https:\/\/www.ecovis.com\/muenchen\/beratungsschwerpunkte\/rechtsberatung\/erbrecht\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ecovis.com\/muenchen\/beratungsschwerpunkte\/rechtsberatung\/erbrecht\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ecovis.com\/muenchen\/beratungsschwerpunkte\/rechtsberatung\/erbrecht\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Ecovis Global","item":"https:\/\/www.ecovis.com\/"},{"@type":"ListItem","position":2,"name":"Home","item":"https:\/\/www.ecovis.com\/muenchen\/"},{"@type":"ListItem","position":3,"name":"Schwerpunkte","item":"https:\/\/www.ecovis.com\/muenchen\/beratungsschwerpunkte\/"},{"@type":"ListItem","position":4,"name":"Rechtsberatung","item":"https:\/\/www.ecovis.com\/muenchen\/beratungsschwerpunkte\/rechtsberatung\/"},{"@type":"ListItem","position":5,"name":"Erbrecht"}]},{"@type":"WebSite","@id":"https:\/\/www.ecovis.com\/muenchen\/#website","url":"https:\/\/www.ecovis.com\/muenchen\/","name":"Ecovis.com","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ecovis.com\/muenchen\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.ecovis.com\/muenchen\/wp-json\/wp\/v2\/pages\/4685","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecovis.com\/muenchen\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ecovis.com\/muenchen\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecovis.com\/muenchen\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecovis.com\/muenchen\/wp-json\/wp\/v2\/comments?post=4685"}],"version-history":[{"count":2,"href":"https:\/\/www.ecovis.com\/muenchen\/wp-json\/wp\/v2\/pages\/4685\/revisions"}],"predecessor-version":[{"id":4687,"href":"https:\/\/www.ecovis.com\/muenchen\/wp-json\/wp\/v2\/pages\/4685\/revisions\/4687"}],"up":[{"embeddable":true,"href":"https:\/\/www.ecovis.com\/muenchen\/wp-json\/wp\/v2\/pages\/3778"}],"wp:attachment":[{"href":"https:\/\/www.ecovis.com\/muenchen\/wp-json\/wp\/v2\/media?parent=4685"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}