{"id":4043,"date":"2026-07-08T13:46:30","date_gmt":"2026-07-08T11:46:30","guid":{"rendered":"https:\/\/www.ecovis.com\/merchweiler\/?page_id=4043"},"modified":"2026-07-08T14:18:00","modified_gmt":"2026-07-08T12:18:00","slug":"gesundheitswesen","status":"publish","type":"page","link":"https:\/\/www.ecovis.com\/merchweiler\/beratungsschwerpunkte\/gesundheitswesen\/","title":{"rendered":"Gesundheitswesen"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":26,"featured_media":0,"parent":3107,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"leistungen-gesundheitswesen.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-4043","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ECOVIS Merchweiler Steuerberater - Gesundheitswesen<\/title>\n<meta name=\"description\" content=\"ECOVIS Merchweiler betreut \u00c4rztinnen, \u00c4rzte und Unternehmen im Gesundheitswesen in allen steuerlichen und wirtschaftlichen Fragen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecovis.com\/merchweiler\/beratungsschwerpunkte\/gesundheitswesen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ECOVIS Merchweiler Steuerberater - Gesundheitswesen\" \/>\n<meta property=\"og:description\" content=\"ECOVIS Merchweiler betreut \u00c4rztinnen, \u00c4rzte und Unternehmen im Gesundheitswesen in allen steuerlichen und wirtschaftlichen Fragen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecovis.com\/merchweiler\/beratungsschwerpunkte\/gesundheitswesen\/\" \/>\n<meta property=\"og:site_name\" content=\"Ecovis Merchweiler\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-08T12:18:00+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ecovis.com\\\/merchweiler\\\/beratungsschwerpunkte\\\/gesundheitswesen\\\/\",\"url\":\"https:\\\/\\\/www.ecovis.com\\\/merchweiler\\\/beratungsschwerpunkte\\\/gesundheitswesen\\\/\",\"name\":\"ECOVIS Merchweiler Steuerberater - Gesundheitswesen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ecovis.com\\\/merchweiler\\\/#website\"},\"datePublished\":\"2026-07-08T11:46:30+00:00\",\"dateModified\":\"2026-07-08T12:18:00+00:00\",\"description\":\"ECOVIS Merchweiler betreut \u00c4rztinnen, \u00c4rzte und Unternehmen im Gesundheitswesen in allen steuerlichen und wirtschaftlichen Fragen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ecovis.com\\\/merchweiler\\\/beratungsschwerpunkte\\\/gesundheitswesen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ecovis.com\\\/merchweiler\\\/beratungsschwerpunkte\\\/gesundheitswesen\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ecovis.com\\\/merchweiler\\\/beratungsschwerpunkte\\\/gesundheitswesen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Ecovis Global\",\"item\":\"https:\\\/\\\/www.ecovis.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ecovis.com\\\/merchweiler\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Beratungsschwerpunkte\",\"item\":\"https:\\\/\\\/www.ecovis.com\\\/merchweiler\\\/beratungsschwerpunkte\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Gesundheitswesen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ecovis.com\\\/merchweiler\\\/#website\",\"url\":\"https:\\\/\\\/www.ecovis.com\\\/merchweiler\\\/\",\"name\":\"Ecovis.com\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ecovis.com\\\/merchweiler\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ECOVIS Merchweiler Steuerberater - Gesundheitswesen","description":"ECOVIS Merchweiler betreut \u00c4rztinnen, \u00c4rzte und Unternehmen im Gesundheitswesen in allen steuerlichen und wirtschaftlichen Fragen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecovis.com\/merchweiler\/beratungsschwerpunkte\/gesundheitswesen\/","og_locale":"de_DE","og_type":"article","og_title":"ECOVIS Merchweiler Steuerberater - Gesundheitswesen","og_description":"ECOVIS Merchweiler betreut \u00c4rztinnen, \u00c4rzte und Unternehmen im Gesundheitswesen in allen steuerlichen und wirtschaftlichen Fragen.","og_url":"https:\/\/www.ecovis.com\/merchweiler\/beratungsschwerpunkte\/gesundheitswesen\/","og_site_name":"Ecovis Merchweiler","article_modified_time":"2026-07-08T12:18:00+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ecovis.com\/merchweiler\/beratungsschwerpunkte\/gesundheitswesen\/","url":"https:\/\/www.ecovis.com\/merchweiler\/beratungsschwerpunkte\/gesundheitswesen\/","name":"ECOVIS Merchweiler Steuerberater - Gesundheitswesen","isPartOf":{"@id":"https:\/\/www.ecovis.com\/merchweiler\/#website"},"datePublished":"2026-07-08T11:46:30+00:00","dateModified":"2026-07-08T12:18:00+00:00","description":"ECOVIS Merchweiler betreut \u00c4rztinnen, \u00c4rzte und Unternehmen im Gesundheitswesen in allen steuerlichen und wirtschaftlichen Fragen.","breadcrumb":{"@id":"https:\/\/www.ecovis.com\/merchweiler\/beratungsschwerpunkte\/gesundheitswesen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ecovis.com\/merchweiler\/beratungsschwerpunkte\/gesundheitswesen\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ecovis.com\/merchweiler\/beratungsschwerpunkte\/gesundheitswesen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Ecovis Global","item":"https:\/\/www.ecovis.com\/"},{"@type":"ListItem","position":2,"name":"Home","item":"https:\/\/www.ecovis.com\/merchweiler\/"},{"@type":"ListItem","position":3,"name":"Beratungsschwerpunkte","item":"https:\/\/www.ecovis.com\/merchweiler\/beratungsschwerpunkte\/"},{"@type":"ListItem","position":4,"name":"Gesundheitswesen"}]},{"@type":"WebSite","@id":"https:\/\/www.ecovis.com\/merchweiler\/#website","url":"https:\/\/www.ecovis.com\/merchweiler\/","name":"Ecovis.com","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ecovis.com\/merchweiler\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.ecovis.com\/merchweiler\/wp-json\/wp\/v2\/pages\/4043","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecovis.com\/merchweiler\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ecovis.com\/merchweiler\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecovis.com\/merchweiler\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecovis.com\/merchweiler\/wp-json\/wp\/v2\/comments?post=4043"}],"version-history":[{"count":1,"href":"https:\/\/www.ecovis.com\/merchweiler\/wp-json\/wp\/v2\/pages\/4043\/revisions"}],"predecessor-version":[{"id":4045,"href":"https:\/\/www.ecovis.com\/merchweiler\/wp-json\/wp\/v2\/pages\/4043\/revisions\/4045"}],"up":[{"embeddable":true,"href":"https:\/\/www.ecovis.com\/merchweiler\/wp-json\/wp\/v2\/pages\/3107"}],"wp:attachment":[{"href":"https:\/\/www.ecovis.com\/merchweiler\/wp-json\/wp\/v2\/media?parent=4043"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}