{"id":3805,"date":"2025-03-25T17:47:29","date_gmt":"2025-03-25T16:47:29","guid":{"rendered":"https:\/\/www.ecovis.com\/b31_lichtenfels\/?page_id=3805"},"modified":"2025-10-22T11:36:26","modified_gmt":"2025-10-22T09:36:26","slug":"startseite","status":"publish","type":"page","link":"https:\/\/www.ecovis.com\/lichtenfels\/","title":{"rendered":"Startseite"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":30,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"services.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-3805","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ECOVIS Lichtenfels, Steuerberater - Pers\u00f6nlich gut beraten<\/title>\n<meta name=\"description\" content=\"Ihre Steuerberater in Lichtenfels, Oberfranken. Rufen Sie uns an und lassen Sie sich pers\u00f6nlich gut beraten, Tel.: +49 9571-94 71 0.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecovis.com\/lichtenfels\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ECOVIS Lichtenfels, Steuerberater - Pers\u00f6nlich gut beraten\" \/>\n<meta property=\"og:description\" content=\"Ihre Steuerberater in Lichtenfels, Oberfranken. Rufen Sie uns an und lassen Sie sich pers\u00f6nlich gut beraten, Tel.: +49 9571-94 71 0.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecovis.com\/lichtenfels\/\" \/>\n<meta property=\"og:site_name\" content=\"Ecovis Lichtenfels\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-22T09:36:26+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ecovis.com\\\/lichtenfels\\\/\",\"url\":\"https:\\\/\\\/www.ecovis.com\\\/lichtenfels\\\/\",\"name\":\"ECOVIS Lichtenfels, Steuerberater - Pers\u00f6nlich gut beraten\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ecovis.com\\\/lichtenfels\\\/#website\"},\"datePublished\":\"2025-03-25T16:47:29+00:00\",\"dateModified\":\"2025-10-22T09:36:26+00:00\",\"description\":\"Ihre Steuerberater in Lichtenfels, Oberfranken. Rufen Sie uns an und lassen Sie sich pers\u00f6nlich gut beraten, Tel.: +49 9571-94 71 0.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ecovis.com\\\/lichtenfels\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ecovis.com\\\/lichtenfels\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ecovis.com\\\/lichtenfels\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Ecovis Global\",\"item\":\"https:\\\/\\\/www.ecovis.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ecovis.com\\\/lichtenfels\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Startseite\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ecovis.com\\\/lichtenfels\\\/#website\",\"url\":\"https:\\\/\\\/www.ecovis.com\\\/lichtenfels\\\/\",\"name\":\"Ecovis.com\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ecovis.com\\\/lichtenfels\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ECOVIS Lichtenfels, Steuerberater - Pers\u00f6nlich gut beraten","description":"Ihre Steuerberater in Lichtenfels, Oberfranken. Rufen Sie uns an und lassen Sie sich pers\u00f6nlich gut beraten, Tel.: +49 9571-94 71 0.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecovis.com\/lichtenfels\/","og_locale":"de_DE","og_type":"article","og_title":"ECOVIS Lichtenfels, Steuerberater - Pers\u00f6nlich gut beraten","og_description":"Ihre Steuerberater in Lichtenfels, Oberfranken. Rufen Sie uns an und lassen Sie sich pers\u00f6nlich gut beraten, Tel.: +49 9571-94 71 0.","og_url":"https:\/\/www.ecovis.com\/lichtenfels\/","og_site_name":"Ecovis Lichtenfels","article_modified_time":"2025-10-22T09:36:26+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ecovis.com\/lichtenfels\/","url":"https:\/\/www.ecovis.com\/lichtenfels\/","name":"ECOVIS Lichtenfels, Steuerberater - Pers\u00f6nlich gut beraten","isPartOf":{"@id":"https:\/\/www.ecovis.com\/lichtenfels\/#website"},"datePublished":"2025-03-25T16:47:29+00:00","dateModified":"2025-10-22T09:36:26+00:00","description":"Ihre Steuerberater in Lichtenfels, Oberfranken. Rufen Sie uns an und lassen Sie sich pers\u00f6nlich gut beraten, Tel.: +49 9571-94 71 0.","breadcrumb":{"@id":"https:\/\/www.ecovis.com\/lichtenfels\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ecovis.com\/lichtenfels\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ecovis.com\/lichtenfels\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Ecovis Global","item":"https:\/\/www.ecovis.com\/"},{"@type":"ListItem","position":2,"name":"Home","item":"https:\/\/www.ecovis.com\/lichtenfels\/"},{"@type":"ListItem","position":3,"name":"Startseite"}]},{"@type":"WebSite","@id":"https:\/\/www.ecovis.com\/lichtenfels\/#website","url":"https:\/\/www.ecovis.com\/lichtenfels\/","name":"Ecovis.com","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ecovis.com\/lichtenfels\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.ecovis.com\/lichtenfels\/wp-json\/wp\/v2\/pages\/3805","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecovis.com\/lichtenfels\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ecovis.com\/lichtenfels\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecovis.com\/lichtenfels\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecovis.com\/lichtenfels\/wp-json\/wp\/v2\/comments?post=3805"}],"version-history":[{"count":59,"href":"https:\/\/www.ecovis.com\/lichtenfels\/wp-json\/wp\/v2\/pages\/3805\/revisions"}],"predecessor-version":[{"id":4395,"href":"https:\/\/www.ecovis.com\/lichtenfels\/wp-json\/wp\/v2\/pages\/3805\/revisions\/4395"}],"wp:attachment":[{"href":"https:\/\/www.ecovis.com\/lichtenfels\/wp-json\/wp\/v2\/media?parent=3805"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}