{"id":4007,"date":"2025-10-11T11:14:07","date_gmt":"2025-10-11T09:14:07","guid":{"rendered":"https:\/\/www.ecovis.com\/a36-kirchheim\/?page_id=4007"},"modified":"2025-10-13T09:43:41","modified_gmt":"2025-10-13T07:43:41","slug":"unternehmensnachfolge","status":"publish","type":"page","link":"https:\/\/www.ecovis.com\/kirchheim\/beratungsschwerpunkte\/unternehmensnachfolge\/","title":{"rendered":"Unternehmensnachfolge"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":31,"featured_media":0,"parent":3771,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"leistungen-unternehmensnachfolge.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-4007","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ecovis Kirchheim - Unternehmensnachfolge<\/title>\n<meta name=\"description\" content=\"Ihr Partner f\u00fcr eine erfolgreiche Unternehmens\u00fcbergabe. Juristische, steuerliche und betriebswirtschaftliche Expertise aus einer Hand.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecovis.com\/kirchheim\/beratungsschwerpunkte\/unternehmensnachfolge\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ecovis Kirchheim - Unternehmensnachfolge\" \/>\n<meta property=\"og:description\" content=\"Ihr Partner f\u00fcr eine erfolgreiche Unternehmens\u00fcbergabe. Juristische, steuerliche und betriebswirtschaftliche Expertise aus einer Hand.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecovis.com\/kirchheim\/beratungsschwerpunkte\/unternehmensnachfolge\/\" \/>\n<meta property=\"og:site_name\" content=\"Ecovis Kirchheim\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-13T07:43:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ecovis.com\\\/kirchheim\\\/beratungsschwerpunkte\\\/unternehmensnachfolge\\\/\",\"url\":\"https:\\\/\\\/www.ecovis.com\\\/kirchheim\\\/beratungsschwerpunkte\\\/unternehmensnachfolge\\\/\",\"name\":\"Ecovis Kirchheim - Unternehmensnachfolge\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ecovis.com\\\/kirchheim\\\/#website\"},\"datePublished\":\"2025-10-11T09:14:07+00:00\",\"dateModified\":\"2025-10-13T07:43:41+00:00\",\"description\":\"Ihr Partner f\u00fcr eine erfolgreiche Unternehmens\u00fcbergabe. Juristische, steuerliche und betriebswirtschaftliche Expertise aus einer Hand.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ecovis.com\\\/kirchheim\\\/beratungsschwerpunkte\\\/unternehmensnachfolge\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ecovis.com\\\/kirchheim\\\/beratungsschwerpunkte\\\/unternehmensnachfolge\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ecovis.com\\\/kirchheim\\\/beratungsschwerpunkte\\\/unternehmensnachfolge\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Ecovis Global\",\"item\":\"https:\\\/\\\/www.ecovis.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ecovis.com\\\/kirchheim\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Schwerpunkte\",\"item\":\"https:\\\/\\\/www.ecovis.com\\\/kirchheim\\\/beratungsschwerpunkte\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Unternehmensnachfolge\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ecovis.com\\\/kirchheim\\\/#website\",\"url\":\"https:\\\/\\\/www.ecovis.com\\\/kirchheim\\\/\",\"name\":\"Ecovis.com\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ecovis.com\\\/kirchheim\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ecovis Kirchheim - Unternehmensnachfolge","description":"Ihr Partner f\u00fcr eine erfolgreiche Unternehmens\u00fcbergabe. Juristische, steuerliche und betriebswirtschaftliche Expertise aus einer Hand.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecovis.com\/kirchheim\/beratungsschwerpunkte\/unternehmensnachfolge\/","og_locale":"de_DE","og_type":"article","og_title":"Ecovis Kirchheim - Unternehmensnachfolge","og_description":"Ihr Partner f\u00fcr eine erfolgreiche Unternehmens\u00fcbergabe. Juristische, steuerliche und betriebswirtschaftliche Expertise aus einer Hand.","og_url":"https:\/\/www.ecovis.com\/kirchheim\/beratungsschwerpunkte\/unternehmensnachfolge\/","og_site_name":"Ecovis Kirchheim","article_modified_time":"2025-10-13T07:43:41+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ecovis.com\/kirchheim\/beratungsschwerpunkte\/unternehmensnachfolge\/","url":"https:\/\/www.ecovis.com\/kirchheim\/beratungsschwerpunkte\/unternehmensnachfolge\/","name":"Ecovis Kirchheim - Unternehmensnachfolge","isPartOf":{"@id":"https:\/\/www.ecovis.com\/kirchheim\/#website"},"datePublished":"2025-10-11T09:14:07+00:00","dateModified":"2025-10-13T07:43:41+00:00","description":"Ihr Partner f\u00fcr eine erfolgreiche Unternehmens\u00fcbergabe. Juristische, steuerliche und betriebswirtschaftliche Expertise aus einer Hand.","breadcrumb":{"@id":"https:\/\/www.ecovis.com\/kirchheim\/beratungsschwerpunkte\/unternehmensnachfolge\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ecovis.com\/kirchheim\/beratungsschwerpunkte\/unternehmensnachfolge\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ecovis.com\/kirchheim\/beratungsschwerpunkte\/unternehmensnachfolge\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Ecovis Global","item":"https:\/\/www.ecovis.com\/"},{"@type":"ListItem","position":2,"name":"Home","item":"https:\/\/www.ecovis.com\/kirchheim\/"},{"@type":"ListItem","position":3,"name":"Schwerpunkte","item":"https:\/\/www.ecovis.com\/kirchheim\/beratungsschwerpunkte\/"},{"@type":"ListItem","position":4,"name":"Unternehmensnachfolge"}]},{"@type":"WebSite","@id":"https:\/\/www.ecovis.com\/kirchheim\/#website","url":"https:\/\/www.ecovis.com\/kirchheim\/","name":"Ecovis.com","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ecovis.com\/kirchheim\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.ecovis.com\/kirchheim\/wp-json\/wp\/v2\/pages\/4007","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecovis.com\/kirchheim\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ecovis.com\/kirchheim\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecovis.com\/kirchheim\/wp-json\/wp\/v2\/users\/31"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecovis.com\/kirchheim\/wp-json\/wp\/v2\/comments?post=4007"}],"version-history":[{"count":2,"href":"https:\/\/www.ecovis.com\/kirchheim\/wp-json\/wp\/v2\/pages\/4007\/revisions"}],"predecessor-version":[{"id":4417,"href":"https:\/\/www.ecovis.com\/kirchheim\/wp-json\/wp\/v2\/pages\/4007\/revisions\/4417"}],"up":[{"embeddable":true,"href":"https:\/\/www.ecovis.com\/kirchheim\/wp-json\/wp\/v2\/pages\/3771"}],"wp:attachment":[{"href":"https:\/\/www.ecovis.com\/kirchheim\/wp-json\/wp\/v2\/media?parent=4007"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}