{"id":4056,"date":"2025-10-08T15:52:45","date_gmt":"2025-10-08T13:52:45","guid":{"rendered":"https:\/\/www.ecovis.com\/a33-hamburg-stb\/?page_id=4056"},"modified":"2025-10-08T15:52:45","modified_gmt":"2025-10-08T13:52:45","slug":"gesundheitswesen","status":"publish","type":"page","link":"https:\/\/www.ecovis.com\/hamburg-stb\/beratungsschwerpunkte\/gesundheitswesen\/","title":{"rendered":"Gesundheitswesen"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":31,"featured_media":0,"parent":3771,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"leistungen-gesundheitswesen.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-4056","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ecovis Hamburg Steuerberater - Gesundheitswesen<\/title>\n<meta name=\"description\" content=\"Beratung in Hamburg f\u00fcr \u00c4rzte, Zahn\u00e4rzte, Apotheken und andere Dienstleister im Gesundheitswesen - Jetzt Termin vereinbaren!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecovis.com\/hamburg-stb\/beratungsschwerpunkte\/gesundheitswesen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ecovis Hamburg Steuerberater - Gesundheitswesen\" \/>\n<meta property=\"og:description\" content=\"Beratung in Hamburg f\u00fcr \u00c4rzte, Zahn\u00e4rzte, Apotheken und andere Dienstleister im Gesundheitswesen - Jetzt Termin vereinbaren!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecovis.com\/hamburg-stb\/beratungsschwerpunkte\/gesundheitswesen\/\" \/>\n<meta property=\"og:site_name\" content=\"Ecovis Hamburg STB\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ecovis.com\\\/hamburg-stb\\\/beratungsschwerpunkte\\\/gesundheitswesen\\\/\",\"url\":\"https:\\\/\\\/www.ecovis.com\\\/hamburg-stb\\\/beratungsschwerpunkte\\\/gesundheitswesen\\\/\",\"name\":\"Ecovis Hamburg Steuerberater - Gesundheitswesen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ecovis.com\\\/hamburg-stb\\\/#website\"},\"datePublished\":\"2025-10-08T13:52:45+00:00\",\"description\":\"Beratung in Hamburg f\u00fcr \u00c4rzte, Zahn\u00e4rzte, Apotheken und andere Dienstleister im Gesundheitswesen - Jetzt Termin vereinbaren!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ecovis.com\\\/hamburg-stb\\\/beratungsschwerpunkte\\\/gesundheitswesen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ecovis.com\\\/hamburg-stb\\\/beratungsschwerpunkte\\\/gesundheitswesen\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ecovis.com\\\/hamburg-stb\\\/beratungsschwerpunkte\\\/gesundheitswesen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Ecovis Global\",\"item\":\"https:\\\/\\\/www.ecovis.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ecovis.com\\\/hamburg-stb\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Schwerpunkte\",\"item\":\"https:\\\/\\\/www.ecovis.com\\\/hamburg-stb\\\/beratungsschwerpunkte\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Gesundheitswesen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ecovis.com\\\/hamburg-stb\\\/#website\",\"url\":\"https:\\\/\\\/www.ecovis.com\\\/hamburg-stb\\\/\",\"name\":\"Ecovis.com\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ecovis.com\\\/hamburg-stb\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ecovis Hamburg Steuerberater - Gesundheitswesen","description":"Beratung in Hamburg f\u00fcr \u00c4rzte, Zahn\u00e4rzte, Apotheken und andere Dienstleister im Gesundheitswesen - Jetzt Termin vereinbaren!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecovis.com\/hamburg-stb\/beratungsschwerpunkte\/gesundheitswesen\/","og_locale":"de_DE","og_type":"article","og_title":"Ecovis Hamburg Steuerberater - Gesundheitswesen","og_description":"Beratung in Hamburg f\u00fcr \u00c4rzte, Zahn\u00e4rzte, Apotheken und andere Dienstleister im Gesundheitswesen - Jetzt Termin vereinbaren!","og_url":"https:\/\/www.ecovis.com\/hamburg-stb\/beratungsschwerpunkte\/gesundheitswesen\/","og_site_name":"Ecovis Hamburg STB","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ecovis.com\/hamburg-stb\/beratungsschwerpunkte\/gesundheitswesen\/","url":"https:\/\/www.ecovis.com\/hamburg-stb\/beratungsschwerpunkte\/gesundheitswesen\/","name":"Ecovis Hamburg Steuerberater - Gesundheitswesen","isPartOf":{"@id":"https:\/\/www.ecovis.com\/hamburg-stb\/#website"},"datePublished":"2025-10-08T13:52:45+00:00","description":"Beratung in Hamburg f\u00fcr \u00c4rzte, Zahn\u00e4rzte, Apotheken und andere Dienstleister im Gesundheitswesen - Jetzt Termin vereinbaren!","breadcrumb":{"@id":"https:\/\/www.ecovis.com\/hamburg-stb\/beratungsschwerpunkte\/gesundheitswesen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ecovis.com\/hamburg-stb\/beratungsschwerpunkte\/gesundheitswesen\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ecovis.com\/hamburg-stb\/beratungsschwerpunkte\/gesundheitswesen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Ecovis Global","item":"https:\/\/www.ecovis.com\/"},{"@type":"ListItem","position":2,"name":"Home","item":"https:\/\/www.ecovis.com\/hamburg-stb\/"},{"@type":"ListItem","position":3,"name":"Schwerpunkte","item":"https:\/\/www.ecovis.com\/hamburg-stb\/beratungsschwerpunkte\/"},{"@type":"ListItem","position":4,"name":"Gesundheitswesen"}]},{"@type":"WebSite","@id":"https:\/\/www.ecovis.com\/hamburg-stb\/#website","url":"https:\/\/www.ecovis.com\/hamburg-stb\/","name":"Ecovis.com","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ecovis.com\/hamburg-stb\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.ecovis.com\/hamburg-stb\/wp-json\/wp\/v2\/pages\/4056","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecovis.com\/hamburg-stb\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ecovis.com\/hamburg-stb\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecovis.com\/hamburg-stb\/wp-json\/wp\/v2\/users\/31"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecovis.com\/hamburg-stb\/wp-json\/wp\/v2\/comments?post=4056"}],"version-history":[{"count":1,"href":"https:\/\/www.ecovis.com\/hamburg-stb\/wp-json\/wp\/v2\/pages\/4056\/revisions"}],"predecessor-version":[{"id":4057,"href":"https:\/\/www.ecovis.com\/hamburg-stb\/wp-json\/wp\/v2\/pages\/4056\/revisions\/4057"}],"up":[{"embeddable":true,"href":"https:\/\/www.ecovis.com\/hamburg-stb\/wp-json\/wp\/v2\/pages\/3771"}],"wp:attachment":[{"href":"https:\/\/www.ecovis.com\/hamburg-stb\/wp-json\/wp\/v2\/media?parent=4056"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}