{"id":3924,"date":"2025-10-08T15:07:25","date_gmt":"2025-10-08T13:07:25","guid":{"rendered":"https:\/\/www.ecovis.com\/a32-haag\/?page_id=3924"},"modified":"2025-10-08T15:09:58","modified_gmt":"2025-10-08T13:09:58","slug":"handwerk","status":"publish","type":"page","link":"https:\/\/www.ecovis.com\/haag\/beratungsschwerpunkte\/handwerk\/","title":{"rendered":"Handwerk"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":31,"featured_media":0,"parent":3771,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"leistungen-handwerk.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-3924","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ecovis Haag - Steuerberatung f\u00fcr Handwerksbetriebe<\/title>\n<meta name=\"description\" content=\"Ecovis Haag kennt die Herausforderungen im Handwerk \u2013 wir beraten Sie steuerlich, rechtlich &amp; unternehmerisch aus einer Hand.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecovis.com\/haag\/beratungsschwerpunkte\/handwerk\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ecovis Haag - Steuerberatung f\u00fcr Handwerksbetriebe\" \/>\n<meta property=\"og:description\" content=\"Ecovis Haag kennt die Herausforderungen im Handwerk \u2013 wir beraten Sie steuerlich, rechtlich &amp; unternehmerisch aus einer Hand.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecovis.com\/haag\/beratungsschwerpunkte\/handwerk\/\" \/>\n<meta property=\"og:site_name\" content=\"Ecovis Haag\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-08T13:09:58+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ecovis.com\\\/haag\\\/beratungsschwerpunkte\\\/handwerk\\\/\",\"url\":\"https:\\\/\\\/www.ecovis.com\\\/haag\\\/beratungsschwerpunkte\\\/handwerk\\\/\",\"name\":\"Ecovis Haag - Steuerberatung f\u00fcr Handwerksbetriebe\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ecovis.com\\\/haag\\\/#website\"},\"datePublished\":\"2025-10-08T13:07:25+00:00\",\"dateModified\":\"2025-10-08T13:09:58+00:00\",\"description\":\"Ecovis Haag kennt die Herausforderungen im Handwerk \u2013 wir beraten Sie steuerlich, rechtlich & unternehmerisch aus einer Hand.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ecovis.com\\\/haag\\\/beratungsschwerpunkte\\\/handwerk\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ecovis.com\\\/haag\\\/beratungsschwerpunkte\\\/handwerk\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ecovis.com\\\/haag\\\/beratungsschwerpunkte\\\/handwerk\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Ecovis Global\",\"item\":\"https:\\\/\\\/www.ecovis.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ecovis.com\\\/haag\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Schwerpunkte\",\"item\":\"https:\\\/\\\/www.ecovis.com\\\/haag\\\/beratungsschwerpunkte\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Handwerk\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ecovis.com\\\/haag\\\/#website\",\"url\":\"https:\\\/\\\/www.ecovis.com\\\/haag\\\/\",\"name\":\"Ecovis.com\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ecovis.com\\\/haag\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ecovis Haag - Steuerberatung f\u00fcr Handwerksbetriebe","description":"Ecovis Haag kennt die Herausforderungen im Handwerk \u2013 wir beraten Sie steuerlich, rechtlich & unternehmerisch aus einer Hand.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecovis.com\/haag\/beratungsschwerpunkte\/handwerk\/","og_locale":"de_DE","og_type":"article","og_title":"Ecovis Haag - Steuerberatung f\u00fcr Handwerksbetriebe","og_description":"Ecovis Haag kennt die Herausforderungen im Handwerk \u2013 wir beraten Sie steuerlich, rechtlich & unternehmerisch aus einer Hand.","og_url":"https:\/\/www.ecovis.com\/haag\/beratungsschwerpunkte\/handwerk\/","og_site_name":"Ecovis Haag","article_modified_time":"2025-10-08T13:09:58+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ecovis.com\/haag\/beratungsschwerpunkte\/handwerk\/","url":"https:\/\/www.ecovis.com\/haag\/beratungsschwerpunkte\/handwerk\/","name":"Ecovis Haag - Steuerberatung f\u00fcr Handwerksbetriebe","isPartOf":{"@id":"https:\/\/www.ecovis.com\/haag\/#website"},"datePublished":"2025-10-08T13:07:25+00:00","dateModified":"2025-10-08T13:09:58+00:00","description":"Ecovis Haag kennt die Herausforderungen im Handwerk \u2013 wir beraten Sie steuerlich, rechtlich & unternehmerisch aus einer Hand.","breadcrumb":{"@id":"https:\/\/www.ecovis.com\/haag\/beratungsschwerpunkte\/handwerk\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ecovis.com\/haag\/beratungsschwerpunkte\/handwerk\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ecovis.com\/haag\/beratungsschwerpunkte\/handwerk\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Ecovis Global","item":"https:\/\/www.ecovis.com\/"},{"@type":"ListItem","position":2,"name":"Home","item":"https:\/\/www.ecovis.com\/haag\/"},{"@type":"ListItem","position":3,"name":"Schwerpunkte","item":"https:\/\/www.ecovis.com\/haag\/beratungsschwerpunkte\/"},{"@type":"ListItem","position":4,"name":"Handwerk"}]},{"@type":"WebSite","@id":"https:\/\/www.ecovis.com\/haag\/#website","url":"https:\/\/www.ecovis.com\/haag\/","name":"Ecovis.com","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ecovis.com\/haag\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.ecovis.com\/haag\/wp-json\/wp\/v2\/pages\/3924","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecovis.com\/haag\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ecovis.com\/haag\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecovis.com\/haag\/wp-json\/wp\/v2\/users\/31"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecovis.com\/haag\/wp-json\/wp\/v2\/comments?post=3924"}],"version-history":[{"count":2,"href":"https:\/\/www.ecovis.com\/haag\/wp-json\/wp\/v2\/pages\/3924\/revisions"}],"predecessor-version":[{"id":3991,"href":"https:\/\/www.ecovis.com\/haag\/wp-json\/wp\/v2\/pages\/3924\/revisions\/3991"}],"up":[{"embeddable":true,"href":"https:\/\/www.ecovis.com\/haag\/wp-json\/wp\/v2\/pages\/3771"}],"wp:attachment":[{"href":"https:\/\/www.ecovis.com\/haag\/wp-json\/wp\/v2\/media?parent=3924"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}