{"id":4034,"date":"2025-08-02T13:39:15","date_gmt":"2025-08-02T11:39:15","guid":{"rendered":"https:\/\/www.ecovis.com\/b21_eisfeld\/?page_id=4034"},"modified":"2025-08-02T13:44:30","modified_gmt":"2025-08-02T11:44:30","slug":"onlinehandel","status":"publish","type":"page","link":"https:\/\/www.ecovis.com\/eisfeld\/beratungsschwerpunkte\/onlinehandel\/","title":{"rendered":"Onlinehandel \/ E-Commerce"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":28,"featured_media":0,"parent":3771,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"leistungen-onlinehandel.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-4034","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ecovis Eisfeld - Onlinehandel \/ E-Commerce<\/title>\n<meta name=\"description\" content=\"Wir \u00fcbernehmen Ihr Rechnungswesen \u2013 von der Buchhaltung bis zur Steuererkl\u00e4rung. Digital, effizient &amp; rechtssicher.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecovis.com\/eisfeld\/beratungsschwerpunkte\/onlinehandel\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ecovis Eisfeld - Onlinehandel \/ E-Commerce\" \/>\n<meta property=\"og:description\" content=\"Wir \u00fcbernehmen Ihr Rechnungswesen \u2013 von der Buchhaltung bis zur Steuererkl\u00e4rung. Digital, effizient &amp; rechtssicher.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecovis.com\/eisfeld\/beratungsschwerpunkte\/onlinehandel\/\" \/>\n<meta property=\"og:site_name\" content=\"Ecovis Eisfeld\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-02T11:44:30+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ecovis.com\\\/eisfeld\\\/beratungsschwerpunkte\\\/onlinehandel\\\/\",\"url\":\"https:\\\/\\\/www.ecovis.com\\\/eisfeld\\\/beratungsschwerpunkte\\\/onlinehandel\\\/\",\"name\":\"Ecovis Eisfeld - Onlinehandel \\\/ E-Commerce\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ecovis.com\\\/eisfeld\\\/#website\"},\"datePublished\":\"2025-08-02T11:39:15+00:00\",\"dateModified\":\"2025-08-02T11:44:30+00:00\",\"description\":\"Wir \u00fcbernehmen Ihr Rechnungswesen \u2013 von der Buchhaltung bis zur Steuererkl\u00e4rung. Digital, effizient & rechtssicher.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ecovis.com\\\/eisfeld\\\/beratungsschwerpunkte\\\/onlinehandel\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ecovis.com\\\/eisfeld\\\/beratungsschwerpunkte\\\/onlinehandel\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ecovis.com\\\/eisfeld\\\/beratungsschwerpunkte\\\/onlinehandel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Ecovis Global\",\"item\":\"https:\\\/\\\/www.ecovis.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ecovis.com\\\/eisfeld\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Schwerpunkte\",\"item\":\"https:\\\/\\\/www.ecovis.com\\\/eisfeld\\\/beratungsschwerpunkte\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Onlinehandel \\\/ E-Commerce\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ecovis.com\\\/eisfeld\\\/#website\",\"url\":\"https:\\\/\\\/www.ecovis.com\\\/eisfeld\\\/\",\"name\":\"Ecovis.com\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ecovis.com\\\/eisfeld\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ecovis Eisfeld - Onlinehandel \/ E-Commerce","description":"Wir \u00fcbernehmen Ihr Rechnungswesen \u2013 von der Buchhaltung bis zur Steuererkl\u00e4rung. Digital, effizient & rechtssicher.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecovis.com\/eisfeld\/beratungsschwerpunkte\/onlinehandel\/","og_locale":"de_DE","og_type":"article","og_title":"Ecovis Eisfeld - Onlinehandel \/ E-Commerce","og_description":"Wir \u00fcbernehmen Ihr Rechnungswesen \u2013 von der Buchhaltung bis zur Steuererkl\u00e4rung. Digital, effizient & rechtssicher.","og_url":"https:\/\/www.ecovis.com\/eisfeld\/beratungsschwerpunkte\/onlinehandel\/","og_site_name":"Ecovis Eisfeld","article_modified_time":"2025-08-02T11:44:30+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ecovis.com\/eisfeld\/beratungsschwerpunkte\/onlinehandel\/","url":"https:\/\/www.ecovis.com\/eisfeld\/beratungsschwerpunkte\/onlinehandel\/","name":"Ecovis Eisfeld - Onlinehandel \/ E-Commerce","isPartOf":{"@id":"https:\/\/www.ecovis.com\/eisfeld\/#website"},"datePublished":"2025-08-02T11:39:15+00:00","dateModified":"2025-08-02T11:44:30+00:00","description":"Wir \u00fcbernehmen Ihr Rechnungswesen \u2013 von der Buchhaltung bis zur Steuererkl\u00e4rung. Digital, effizient & rechtssicher.","breadcrumb":{"@id":"https:\/\/www.ecovis.com\/eisfeld\/beratungsschwerpunkte\/onlinehandel\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ecovis.com\/eisfeld\/beratungsschwerpunkte\/onlinehandel\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ecovis.com\/eisfeld\/beratungsschwerpunkte\/onlinehandel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Ecovis Global","item":"https:\/\/www.ecovis.com\/"},{"@type":"ListItem","position":2,"name":"Home","item":"https:\/\/www.ecovis.com\/eisfeld\/"},{"@type":"ListItem","position":3,"name":"Schwerpunkte","item":"https:\/\/www.ecovis.com\/eisfeld\/beratungsschwerpunkte\/"},{"@type":"ListItem","position":4,"name":"Onlinehandel \/ E-Commerce"}]},{"@type":"WebSite","@id":"https:\/\/www.ecovis.com\/eisfeld\/#website","url":"https:\/\/www.ecovis.com\/eisfeld\/","name":"Ecovis.com","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ecovis.com\/eisfeld\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.ecovis.com\/eisfeld\/wp-json\/wp\/v2\/pages\/4034","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecovis.com\/eisfeld\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ecovis.com\/eisfeld\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecovis.com\/eisfeld\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecovis.com\/eisfeld\/wp-json\/wp\/v2\/comments?post=4034"}],"version-history":[{"count":2,"href":"https:\/\/www.ecovis.com\/eisfeld\/wp-json\/wp\/v2\/pages\/4034\/revisions"}],"predecessor-version":[{"id":4043,"href":"https:\/\/www.ecovis.com\/eisfeld\/wp-json\/wp\/v2\/pages\/4034\/revisions\/4043"}],"up":[{"embeddable":true,"href":"https:\/\/www.ecovis.com\/eisfeld\/wp-json\/wp\/v2\/pages\/3771"}],"wp:attachment":[{"href":"https:\/\/www.ecovis.com\/eisfeld\/wp-json\/wp\/v2\/media?parent=4034"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}