{"id":4227,"date":"2025-07-14T13:46:16","date_gmt":"2025-07-14T11:46:16","guid":{"rendered":"https:\/\/www.ecovis.com\/a23-dresden\/?page_id=4227"},"modified":"2025-07-14T14:31:24","modified_gmt":"2025-07-14T12:31:24","slug":"unternehmensberatung","status":"publish","type":"page","link":"https:\/\/www.ecovis.com\/dresden\/beratungsschwerpunkte\/unternehmensberatung\/","title":{"rendered":"Unternehmensberatung"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":28,"featured_media":0,"parent":3771,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"leistungen-unternehmensberatung.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-4227","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ecovis Dresden - Unternehmensberatung<\/title>\n<meta name=\"description\" content=\"Die Ecovis Unternehmensberater begleiten Unternehmer in allen Phasen: Gr\u00fcndung, Wachstum, Digitalisierung, Nachfolge, Sanierung und mehr.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecovis.com\/dresden\/beratungsschwerpunkte\/unternehmensberatung\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ecovis Dresden - Unternehmensberatung\" \/>\n<meta property=\"og:description\" content=\"Die Ecovis Unternehmensberater begleiten Unternehmer in allen Phasen: Gr\u00fcndung, Wachstum, Digitalisierung, Nachfolge, Sanierung und mehr.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecovis.com\/dresden\/beratungsschwerpunkte\/unternehmensberatung\/\" \/>\n<meta property=\"og:site_name\" content=\"Ecovis Dresden\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-14T12:31:24+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ecovis.com\\\/dresden\\\/beratungsschwerpunkte\\\/unternehmensberatung\\\/\",\"url\":\"https:\\\/\\\/www.ecovis.com\\\/dresden\\\/beratungsschwerpunkte\\\/unternehmensberatung\\\/\",\"name\":\"Ecovis Dresden - Unternehmensberatung\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ecovis.com\\\/dresden\\\/#website\"},\"datePublished\":\"2025-07-14T11:46:16+00:00\",\"dateModified\":\"2025-07-14T12:31:24+00:00\",\"description\":\"Die Ecovis Unternehmensberater begleiten Unternehmer in allen Phasen: Gr\u00fcndung, Wachstum, Digitalisierung, Nachfolge, Sanierung und mehr.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ecovis.com\\\/dresden\\\/beratungsschwerpunkte\\\/unternehmensberatung\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ecovis.com\\\/dresden\\\/beratungsschwerpunkte\\\/unternehmensberatung\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ecovis.com\\\/dresden\\\/beratungsschwerpunkte\\\/unternehmensberatung\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Ecovis Global\",\"item\":\"https:\\\/\\\/www.ecovis.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ecovis.com\\\/dresden\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Schwerpunkte\",\"item\":\"https:\\\/\\\/www.ecovis.com\\\/dresden\\\/beratungsschwerpunkte\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Unternehmensberatung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ecovis.com\\\/dresden\\\/#website\",\"url\":\"https:\\\/\\\/www.ecovis.com\\\/dresden\\\/\",\"name\":\"Ecovis.com\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ecovis.com\\\/dresden\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ecovis Dresden - Unternehmensberatung","description":"Die Ecovis Unternehmensberater begleiten Unternehmer in allen Phasen: Gr\u00fcndung, Wachstum, Digitalisierung, Nachfolge, Sanierung und mehr.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecovis.com\/dresden\/beratungsschwerpunkte\/unternehmensberatung\/","og_locale":"de_DE","og_type":"article","og_title":"Ecovis Dresden - Unternehmensberatung","og_description":"Die Ecovis Unternehmensberater begleiten Unternehmer in allen Phasen: Gr\u00fcndung, Wachstum, Digitalisierung, Nachfolge, Sanierung und mehr.","og_url":"https:\/\/www.ecovis.com\/dresden\/beratungsschwerpunkte\/unternehmensberatung\/","og_site_name":"Ecovis Dresden","article_modified_time":"2025-07-14T12:31:24+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ecovis.com\/dresden\/beratungsschwerpunkte\/unternehmensberatung\/","url":"https:\/\/www.ecovis.com\/dresden\/beratungsschwerpunkte\/unternehmensberatung\/","name":"Ecovis Dresden - Unternehmensberatung","isPartOf":{"@id":"https:\/\/www.ecovis.com\/dresden\/#website"},"datePublished":"2025-07-14T11:46:16+00:00","dateModified":"2025-07-14T12:31:24+00:00","description":"Die Ecovis Unternehmensberater begleiten Unternehmer in allen Phasen: Gr\u00fcndung, Wachstum, Digitalisierung, Nachfolge, Sanierung und mehr.","breadcrumb":{"@id":"https:\/\/www.ecovis.com\/dresden\/beratungsschwerpunkte\/unternehmensberatung\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ecovis.com\/dresden\/beratungsschwerpunkte\/unternehmensberatung\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ecovis.com\/dresden\/beratungsschwerpunkte\/unternehmensberatung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Ecovis Global","item":"https:\/\/www.ecovis.com\/"},{"@type":"ListItem","position":2,"name":"Home","item":"https:\/\/www.ecovis.com\/dresden\/"},{"@type":"ListItem","position":3,"name":"Schwerpunkte","item":"https:\/\/www.ecovis.com\/dresden\/beratungsschwerpunkte\/"},{"@type":"ListItem","position":4,"name":"Unternehmensberatung"}]},{"@type":"WebSite","@id":"https:\/\/www.ecovis.com\/dresden\/#website","url":"https:\/\/www.ecovis.com\/dresden\/","name":"Ecovis.com","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ecovis.com\/dresden\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.ecovis.com\/dresden\/wp-json\/wp\/v2\/pages\/4227","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecovis.com\/dresden\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ecovis.com\/dresden\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecovis.com\/dresden\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecovis.com\/dresden\/wp-json\/wp\/v2\/comments?post=4227"}],"version-history":[{"count":4,"href":"https:\/\/www.ecovis.com\/dresden\/wp-json\/wp\/v2\/pages\/4227\/revisions"}],"predecessor-version":[{"id":4488,"href":"https:\/\/www.ecovis.com\/dresden\/wp-json\/wp\/v2\/pages\/4227\/revisions\/4488"}],"up":[{"embeddable":true,"href":"https:\/\/www.ecovis.com\/dresden\/wp-json\/wp\/v2\/pages\/3771"}],"wp:attachment":[{"href":"https:\/\/www.ecovis.com\/dresden\/wp-json\/wp\/v2\/media?parent=4227"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}