{"id":4068,"date":"2025-07-14T13:46:16","date_gmt":"2025-07-14T11:46:16","guid":{"rendered":"https:\/\/www.ecovis.com\/a23-dresden\/?page_id=4068"},"modified":"2025-07-14T14:30:14","modified_gmt":"2025-07-14T12:30:14","slug":"verfahrensdokumentation","status":"publish","type":"page","link":"https:\/\/www.ecovis.com\/dresden\/beratungsschwerpunkte\/verfahrensdokumentation\/","title":{"rendered":"Verfahrensdokumentation"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":28,"featured_media":0,"parent":3771,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"leistungen-verfahrensdokumentation.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-4068","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ecovis Dresden Steuerberater - Verfahrensdokumentation<\/title>\n<meta name=\"description\" content=\"Rechtssicherheit und Effizienz f\u00fcr Ihr Unternehmen. Warum ist eine Verfahrensdokumentation unverzichtbar? Jetzt Termin vereinbaren!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecovis.com\/dresden\/beratungsschwerpunkte\/verfahrensdokumentation\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ecovis Dresden Steuerberater - Verfahrensdokumentation\" \/>\n<meta property=\"og:description\" content=\"Rechtssicherheit und Effizienz f\u00fcr Ihr Unternehmen. Warum ist eine Verfahrensdokumentation unverzichtbar? Jetzt Termin vereinbaren!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecovis.com\/dresden\/beratungsschwerpunkte\/verfahrensdokumentation\/\" \/>\n<meta property=\"og:site_name\" content=\"Ecovis Dresden\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-14T12:30:14+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ecovis.com\\\/dresden\\\/beratungsschwerpunkte\\\/verfahrensdokumentation\\\/\",\"url\":\"https:\\\/\\\/www.ecovis.com\\\/dresden\\\/beratungsschwerpunkte\\\/verfahrensdokumentation\\\/\",\"name\":\"Ecovis Dresden Steuerberater - Verfahrensdokumentation\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ecovis.com\\\/dresden\\\/#website\"},\"datePublished\":\"2025-07-14T11:46:16+00:00\",\"dateModified\":\"2025-07-14T12:30:14+00:00\",\"description\":\"Rechtssicherheit und Effizienz f\u00fcr Ihr Unternehmen. Warum ist eine Verfahrensdokumentation unverzichtbar? Jetzt Termin vereinbaren!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ecovis.com\\\/dresden\\\/beratungsschwerpunkte\\\/verfahrensdokumentation\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ecovis.com\\\/dresden\\\/beratungsschwerpunkte\\\/verfahrensdokumentation\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ecovis.com\\\/dresden\\\/beratungsschwerpunkte\\\/verfahrensdokumentation\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Ecovis Global\",\"item\":\"https:\\\/\\\/www.ecovis.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ecovis.com\\\/dresden\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Schwerpunkte\",\"item\":\"https:\\\/\\\/www.ecovis.com\\\/dresden\\\/beratungsschwerpunkte\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Verfahrensdokumentation\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ecovis.com\\\/dresden\\\/#website\",\"url\":\"https:\\\/\\\/www.ecovis.com\\\/dresden\\\/\",\"name\":\"Ecovis.com\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ecovis.com\\\/dresden\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ecovis Dresden Steuerberater - Verfahrensdokumentation","description":"Rechtssicherheit und Effizienz f\u00fcr Ihr Unternehmen. Warum ist eine Verfahrensdokumentation unverzichtbar? Jetzt Termin vereinbaren!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecovis.com\/dresden\/beratungsschwerpunkte\/verfahrensdokumentation\/","og_locale":"de_DE","og_type":"article","og_title":"Ecovis Dresden Steuerberater - Verfahrensdokumentation","og_description":"Rechtssicherheit und Effizienz f\u00fcr Ihr Unternehmen. Warum ist eine Verfahrensdokumentation unverzichtbar? Jetzt Termin vereinbaren!","og_url":"https:\/\/www.ecovis.com\/dresden\/beratungsschwerpunkte\/verfahrensdokumentation\/","og_site_name":"Ecovis Dresden","article_modified_time":"2025-07-14T12:30:14+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ecovis.com\/dresden\/beratungsschwerpunkte\/verfahrensdokumentation\/","url":"https:\/\/www.ecovis.com\/dresden\/beratungsschwerpunkte\/verfahrensdokumentation\/","name":"Ecovis Dresden Steuerberater - Verfahrensdokumentation","isPartOf":{"@id":"https:\/\/www.ecovis.com\/dresden\/#website"},"datePublished":"2025-07-14T11:46:16+00:00","dateModified":"2025-07-14T12:30:14+00:00","description":"Rechtssicherheit und Effizienz f\u00fcr Ihr Unternehmen. Warum ist eine Verfahrensdokumentation unverzichtbar? Jetzt Termin vereinbaren!","breadcrumb":{"@id":"https:\/\/www.ecovis.com\/dresden\/beratungsschwerpunkte\/verfahrensdokumentation\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ecovis.com\/dresden\/beratungsschwerpunkte\/verfahrensdokumentation\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ecovis.com\/dresden\/beratungsschwerpunkte\/verfahrensdokumentation\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Ecovis Global","item":"https:\/\/www.ecovis.com\/"},{"@type":"ListItem","position":2,"name":"Home","item":"https:\/\/www.ecovis.com\/dresden\/"},{"@type":"ListItem","position":3,"name":"Schwerpunkte","item":"https:\/\/www.ecovis.com\/dresden\/beratungsschwerpunkte\/"},{"@type":"ListItem","position":4,"name":"Verfahrensdokumentation"}]},{"@type":"WebSite","@id":"https:\/\/www.ecovis.com\/dresden\/#website","url":"https:\/\/www.ecovis.com\/dresden\/","name":"Ecovis.com","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ecovis.com\/dresden\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.ecovis.com\/dresden\/wp-json\/wp\/v2\/pages\/4068","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecovis.com\/dresden\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ecovis.com\/dresden\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecovis.com\/dresden\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecovis.com\/dresden\/wp-json\/wp\/v2\/comments?post=4068"}],"version-history":[{"count":3,"href":"https:\/\/www.ecovis.com\/dresden\/wp-json\/wp\/v2\/pages\/4068\/revisions"}],"predecessor-version":[{"id":4487,"href":"https:\/\/www.ecovis.com\/dresden\/wp-json\/wp\/v2\/pages\/4068\/revisions\/4487"}],"up":[{"embeddable":true,"href":"https:\/\/www.ecovis.com\/dresden\/wp-json\/wp\/v2\/pages\/3771"}],"wp:attachment":[{"href":"https:\/\/www.ecovis.com\/dresden\/wp-json\/wp\/v2\/media?parent=4068"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}