{"id":4468,"date":"2025-09-25T17:08:00","date_gmt":"2025-09-25T15:08:00","guid":{"rendered":"https:\/\/www.ecovis.com\/a22-berlin-erp\/?page_id=4468"},"modified":"2025-09-25T17:08:06","modified_gmt":"2025-09-25T15:08:06","slug":"erbrecht","status":"publish","type":"page","link":"https:\/\/www.ecovis.com\/berlin-erp\/rechtsgebiete\/erbrecht\/","title":{"rendered":"Erbrecht"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":30,"featured_media":0,"parent":4431,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"leistungen-erbrecht.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-4468","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ecovis Berlin - Erbrecht<\/title>\n<meta name=\"description\" content=\"Sch\u00fctzen Sie Ihr geistiges Eigentum und vermeiden Sie Rechtsverletzungen. Vereinbaren Sie einen Beratungstermin in Berlin!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecovis.com\/berlin-erp\/rechtsgebiete\/erbrecht\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ecovis Berlin - Erbrecht\" \/>\n<meta property=\"og:description\" content=\"Sch\u00fctzen Sie Ihr geistiges Eigentum und vermeiden Sie Rechtsverletzungen. Vereinbaren Sie einen Beratungstermin in Berlin!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecovis.com\/berlin-erp\/rechtsgebiete\/erbrecht\/\" \/>\n<meta property=\"og:site_name\" content=\"Ecovis Berlin\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-25T15:08:06+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ecovis.com\\\/berlin-erp\\\/rechtsgebiete\\\/erbrecht\\\/\",\"url\":\"https:\\\/\\\/www.ecovis.com\\\/berlin-erp\\\/rechtsgebiete\\\/erbrecht\\\/\",\"name\":\"Ecovis Berlin - Erbrecht\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ecovis.com\\\/berlin-erp\\\/#website\"},\"datePublished\":\"2025-09-25T15:08:00+00:00\",\"dateModified\":\"2025-09-25T15:08:06+00:00\",\"description\":\"Sch\u00fctzen Sie Ihr geistiges Eigentum und vermeiden Sie Rechtsverletzungen. Vereinbaren Sie einen Beratungstermin in Berlin!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ecovis.com\\\/berlin-erp\\\/rechtsgebiete\\\/erbrecht\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ecovis.com\\\/berlin-erp\\\/rechtsgebiete\\\/erbrecht\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ecovis.com\\\/berlin-erp\\\/rechtsgebiete\\\/erbrecht\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Ecovis Global\",\"item\":\"https:\\\/\\\/www.ecovis.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ecovis.com\\\/berlin-erp\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Rechtsgebiete\",\"item\":\"https:\\\/\\\/www.ecovis.com\\\/berlin-erp\\\/rechtsgebiete\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Erbrecht\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ecovis.com\\\/berlin-erp\\\/#website\",\"url\":\"https:\\\/\\\/www.ecovis.com\\\/berlin-erp\\\/\",\"name\":\"Ecovis.com\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ecovis.com\\\/berlin-erp\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ecovis Berlin - Erbrecht","description":"Sch\u00fctzen Sie Ihr geistiges Eigentum und vermeiden Sie Rechtsverletzungen. Vereinbaren Sie einen Beratungstermin in Berlin!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecovis.com\/berlin-erp\/rechtsgebiete\/erbrecht\/","og_locale":"de_DE","og_type":"article","og_title":"Ecovis Berlin - Erbrecht","og_description":"Sch\u00fctzen Sie Ihr geistiges Eigentum und vermeiden Sie Rechtsverletzungen. Vereinbaren Sie einen Beratungstermin in Berlin!","og_url":"https:\/\/www.ecovis.com\/berlin-erp\/rechtsgebiete\/erbrecht\/","og_site_name":"Ecovis Berlin","article_modified_time":"2025-09-25T15:08:06+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ecovis.com\/berlin-erp\/rechtsgebiete\/erbrecht\/","url":"https:\/\/www.ecovis.com\/berlin-erp\/rechtsgebiete\/erbrecht\/","name":"Ecovis Berlin - Erbrecht","isPartOf":{"@id":"https:\/\/www.ecovis.com\/berlin-erp\/#website"},"datePublished":"2025-09-25T15:08:00+00:00","dateModified":"2025-09-25T15:08:06+00:00","description":"Sch\u00fctzen Sie Ihr geistiges Eigentum und vermeiden Sie Rechtsverletzungen. Vereinbaren Sie einen Beratungstermin in Berlin!","breadcrumb":{"@id":"https:\/\/www.ecovis.com\/berlin-erp\/rechtsgebiete\/erbrecht\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ecovis.com\/berlin-erp\/rechtsgebiete\/erbrecht\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ecovis.com\/berlin-erp\/rechtsgebiete\/erbrecht\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Ecovis Global","item":"https:\/\/www.ecovis.com\/"},{"@type":"ListItem","position":2,"name":"Home","item":"https:\/\/www.ecovis.com\/berlin-erp\/"},{"@type":"ListItem","position":3,"name":"Rechtsgebiete","item":"https:\/\/www.ecovis.com\/berlin-erp\/rechtsgebiete\/"},{"@type":"ListItem","position":4,"name":"Erbrecht"}]},{"@type":"WebSite","@id":"https:\/\/www.ecovis.com\/berlin-erp\/#website","url":"https:\/\/www.ecovis.com\/berlin-erp\/","name":"Ecovis.com","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ecovis.com\/berlin-erp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.ecovis.com\/berlin-erp\/wp-json\/wp\/v2\/pages\/4468","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecovis.com\/berlin-erp\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ecovis.com\/berlin-erp\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecovis.com\/berlin-erp\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecovis.com\/berlin-erp\/wp-json\/wp\/v2\/comments?post=4468"}],"version-history":[{"count":1,"href":"https:\/\/www.ecovis.com\/berlin-erp\/wp-json\/wp\/v2\/pages\/4468\/revisions"}],"predecessor-version":[{"id":4469,"href":"https:\/\/www.ecovis.com\/berlin-erp\/wp-json\/wp\/v2\/pages\/4468\/revisions\/4469"}],"up":[{"embeddable":true,"href":"https:\/\/www.ecovis.com\/berlin-erp\/wp-json\/wp\/v2\/pages\/4431"}],"wp:attachment":[{"href":"https:\/\/www.ecovis.com\/berlin-erp\/wp-json\/wp\/v2\/media?parent=4468"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}