{"id":3801,"date":"2025-07-28T14:02:55","date_gmt":"2025-07-28T12:02:55","guid":{"rendered":"https:\/\/www.ecovis.com\/b09_badvilbel\/?page_id=3801"},"modified":"2025-07-28T14:05:15","modified_gmt":"2025-07-28T12:05:15","slug":"steuerberatung","status":"publish","type":"page","link":"https:\/\/www.ecovis.com\/badvilbel\/beratungsschwerpunkte\/steuerberatung\/","title":{"rendered":"Steuerberatung"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":28,"featured_media":0,"parent":3771,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"leistungen-steuerberatung.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-3801","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ecovis Bad Vilbel - Ihre Steuerberater in Wetteraukreis<\/title>\n<meta name=\"description\" content=\"Ihr Partner f\u00fcr Steuerberatung, Finanzplanung &amp; Unternehmensstrategie. F\u00fcr Unternehmen, Freiberufler &amp; Privatpersonen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecovis.com\/badvilbel\/beratungsschwerpunkte\/steuerberatung\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ecovis Bad Vilbel - Ihre Steuerberater in Wetteraukreis\" \/>\n<meta property=\"og:description\" content=\"Ihr Partner f\u00fcr Steuerberatung, Finanzplanung &amp; Unternehmensstrategie. F\u00fcr Unternehmen, Freiberufler &amp; Privatpersonen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecovis.com\/badvilbel\/beratungsschwerpunkte\/steuerberatung\/\" \/>\n<meta property=\"og:site_name\" content=\"Ecovis Bad Vilbel\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-28T12:05:15+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ecovis.com\\\/badvilbel\\\/beratungsschwerpunkte\\\/steuerberatung\\\/\",\"url\":\"https:\\\/\\\/www.ecovis.com\\\/badvilbel\\\/beratungsschwerpunkte\\\/steuerberatung\\\/\",\"name\":\"Ecovis Bad Vilbel - Ihre Steuerberater in Wetteraukreis\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ecovis.com\\\/badvilbel\\\/#website\"},\"datePublished\":\"2025-07-28T12:02:55+00:00\",\"dateModified\":\"2025-07-28T12:05:15+00:00\",\"description\":\"Ihr Partner f\u00fcr Steuerberatung, Finanzplanung & Unternehmensstrategie. F\u00fcr Unternehmen, Freiberufler & Privatpersonen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ecovis.com\\\/badvilbel\\\/beratungsschwerpunkte\\\/steuerberatung\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ecovis.com\\\/badvilbel\\\/beratungsschwerpunkte\\\/steuerberatung\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ecovis.com\\\/badvilbel\\\/beratungsschwerpunkte\\\/steuerberatung\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Ecovis Global\",\"item\":\"https:\\\/\\\/www.ecovis.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ecovis.com\\\/badvilbel\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Schwerpunkte\",\"item\":\"https:\\\/\\\/www.ecovis.com\\\/badvilbel\\\/beratungsschwerpunkte\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Steuerberatung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ecovis.com\\\/badvilbel\\\/#website\",\"url\":\"https:\\\/\\\/www.ecovis.com\\\/badvilbel\\\/\",\"name\":\"Ecovis.com\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ecovis.com\\\/badvilbel\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ecovis Bad Vilbel - Ihre Steuerberater in Wetteraukreis","description":"Ihr Partner f\u00fcr Steuerberatung, Finanzplanung & Unternehmensstrategie. F\u00fcr Unternehmen, Freiberufler & Privatpersonen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecovis.com\/badvilbel\/beratungsschwerpunkte\/steuerberatung\/","og_locale":"en_GB","og_type":"article","og_title":"Ecovis Bad Vilbel - Ihre Steuerberater in Wetteraukreis","og_description":"Ihr Partner f\u00fcr Steuerberatung, Finanzplanung & Unternehmensstrategie. F\u00fcr Unternehmen, Freiberufler & Privatpersonen.","og_url":"https:\/\/www.ecovis.com\/badvilbel\/beratungsschwerpunkte\/steuerberatung\/","og_site_name":"Ecovis Bad Vilbel","article_modified_time":"2025-07-28T12:05:15+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ecovis.com\/badvilbel\/beratungsschwerpunkte\/steuerberatung\/","url":"https:\/\/www.ecovis.com\/badvilbel\/beratungsschwerpunkte\/steuerberatung\/","name":"Ecovis Bad Vilbel - Ihre Steuerberater in Wetteraukreis","isPartOf":{"@id":"https:\/\/www.ecovis.com\/badvilbel\/#website"},"datePublished":"2025-07-28T12:02:55+00:00","dateModified":"2025-07-28T12:05:15+00:00","description":"Ihr Partner f\u00fcr Steuerberatung, Finanzplanung & Unternehmensstrategie. F\u00fcr Unternehmen, Freiberufler & Privatpersonen.","breadcrumb":{"@id":"https:\/\/www.ecovis.com\/badvilbel\/beratungsschwerpunkte\/steuerberatung\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ecovis.com\/badvilbel\/beratungsschwerpunkte\/steuerberatung\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ecovis.com\/badvilbel\/beratungsschwerpunkte\/steuerberatung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Ecovis Global","item":"https:\/\/www.ecovis.com\/"},{"@type":"ListItem","position":2,"name":"Home","item":"https:\/\/www.ecovis.com\/badvilbel\/"},{"@type":"ListItem","position":3,"name":"Schwerpunkte","item":"https:\/\/www.ecovis.com\/badvilbel\/beratungsschwerpunkte\/"},{"@type":"ListItem","position":4,"name":"Steuerberatung"}]},{"@type":"WebSite","@id":"https:\/\/www.ecovis.com\/badvilbel\/#website","url":"https:\/\/www.ecovis.com\/badvilbel\/","name":"Ecovis.com","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ecovis.com\/badvilbel\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"_links":{"self":[{"href":"https:\/\/www.ecovis.com\/badvilbel\/wp-json\/wp\/v2\/pages\/3801","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecovis.com\/badvilbel\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ecovis.com\/badvilbel\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecovis.com\/badvilbel\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecovis.com\/badvilbel\/wp-json\/wp\/v2\/comments?post=3801"}],"version-history":[{"count":3,"href":"https:\/\/www.ecovis.com\/badvilbel\/wp-json\/wp\/v2\/pages\/3801\/revisions"}],"predecessor-version":[{"id":3998,"href":"https:\/\/www.ecovis.com\/badvilbel\/wp-json\/wp\/v2\/pages\/3801\/revisions\/3998"}],"up":[{"embeddable":true,"href":"https:\/\/www.ecovis.com\/badvilbel\/wp-json\/wp\/v2\/pages\/3771"}],"wp:attachment":[{"href":"https:\/\/www.ecovis.com\/badvilbel\/wp-json\/wp\/v2\/media?parent=3801"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}